{"id":9412,"date":"2023-05-21T13:58:15","date_gmt":"2023-05-21T12:58:15","guid":{"rendered":"https:\/\/europainversi.org\/wp-content\/uploads\/2023\/05\/2023-05-20_17-45-04_1.jpg"},"modified":"2023-05-21T13:58:15","modified_gmt":"2023-05-21T12:58:15","slug":"2023-05-20_17-45-04_1-2","status":"inherit","type":"attachment","link":"https:\/\/europainversi.org\/en\/2023-05-20_17-45-04_1-2\/","title":{"rendered":"2023-05-20_17-45-04_1"},"author":8,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-9412","attachment","type-attachment","status-inherit","h-entry","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>2023-05-20_17-45-04_1 - Europa in Versi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/europainversi.org\/en\/2023-05-20_17-45-04_1-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2023-05-20_17-45-04_1 - Europa in Versi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/europainversi.org\/en\/2023-05-20_17-45-04_1-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Europa in Versi\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/europainversi\" \/>\n<meta property=\"og:image\" content=\"https:\/\/europainversi.org\/wp-content\/uploads\/2023\/05\/2023-05-20_17-45-04_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@EuropainVersi\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/europainversi.org\\\/en\\\/2023-05-20_17-45-04_1-2\\\/\",\"url\":\"https:\\\/\\\/europainversi.org\\\/en\\\/2023-05-20_17-45-04_1-2\\\/\",\"name\":\"2023-05-20_17-45-04_1 - Europa in Versi\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/europainversi.org\\\/en\\\/#website\"},\"datePublished\":\"2023-05-21T12:58:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/europainversi.org\\\/en\\\/2023-05-20_17-45-04_1-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/europainversi.org\\\/en\\\/2023-05-20_17-45-04_1-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/europainversi.org\\\/en\\\/2023-05-20_17-45-04_1-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/europainversi.org\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"2023-05-20_17-45-04_1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/europainversi.org\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/europainversi.org\\\/en\\\/\",\"name\":\"Europa in Versi\",\"description\":\"Festival Internazionale di Poesia de La Casa della Poesia di Como\",\"publisher\":{\"@id\":\"https:\\\/\\\/europainversi.org\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/europainversi.org\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/europainversi.org\\\/en\\\/#organization\",\"name\":\"Europa In Versi\",\"url\":\"https:\\\/\\\/europainversi.org\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/europainversi.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/europainversi.org\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/cropped-EIV_Logo_Elab_Icon.jpg\",\"contentUrl\":\"https:\\\/\\\/europainversi.org\\\/wp-content\\\/uploads\\\/2016\\\/10\\\/cropped-EIV_Logo_Elab_Icon.jpg\",\"width\":512,\"height\":512,\"caption\":\"Europa In Versi\"},\"image\":{\"@id\":\"https:\\\/\\\/europainversi.org\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/europainversi\",\"https:\\\/\\\/x.com\\\/EuropainVersi\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2023-05-20_17-45-04_1 - Europa in Versi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/europainversi.org\/en\/2023-05-20_17-45-04_1-2\/","og_locale":"en_US","og_type":"article","og_title":"2023-05-20_17-45-04_1 - Europa in Versi","og_url":"https:\/\/europainversi.org\/en\/2023-05-20_17-45-04_1-2\/","og_site_name":"Europa in Versi","article_publisher":"https:\/\/www.facebook.com\/europainversi","og_image":[{"width":1500,"height":1000,"url":"https:\/\/europainversi.org\/wp-content\/uploads\/2023\/05\/2023-05-20_17-45-04_1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@EuropainVersi","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/europainversi.org\/en\/2023-05-20_17-45-04_1-2\/","url":"https:\/\/europainversi.org\/en\/2023-05-20_17-45-04_1-2\/","name":"2023-05-20_17-45-04_1 - Europa in Versi","isPartOf":{"@id":"https:\/\/europainversi.org\/en\/#website"},"datePublished":"2023-05-21T12:58:15+00:00","breadcrumb":{"@id":"https:\/\/europainversi.org\/en\/2023-05-20_17-45-04_1-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/europainversi.org\/en\/2023-05-20_17-45-04_1-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/europainversi.org\/en\/2023-05-20_17-45-04_1-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/europainversi.org\/en\/"},{"@type":"ListItem","position":2,"name":"2023-05-20_17-45-04_1"}]},{"@type":"WebSite","@id":"https:\/\/europainversi.org\/en\/#website","url":"https:\/\/europainversi.org\/en\/","name":"Europa in Versi","description":"Festival Internazionale di Poesia de La Casa della Poesia di Como","publisher":{"@id":"https:\/\/europainversi.org\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/europainversi.org\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/europainversi.org\/en\/#organization","name":"Europa In Versi","url":"https:\/\/europainversi.org\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/europainversi.org\/en\/#\/schema\/logo\/image\/","url":"https:\/\/europainversi.org\/wp-content\/uploads\/2016\/10\/cropped-EIV_Logo_Elab_Icon.jpg","contentUrl":"https:\/\/europainversi.org\/wp-content\/uploads\/2016\/10\/cropped-EIV_Logo_Elab_Icon.jpg","width":512,"height":512,"caption":"Europa In Versi"},"image":{"@id":"https:\/\/europainversi.org\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/europainversi","https:\/\/x.com\/EuropainVersi"]}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/europainversi.org\/wp-content\/uploads\/2023\/05\/2023-05-20_17-45-04_1.jpg' title=\"\" data-rl_title=\"\" class=\"rl-gallery-link\" data-rl_caption=\"\" data-rel=\"lightbox-gallery-0\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/europainversi.org\/wp-content\/uploads\/2023\/05\/2023-05-20_17-45-04_1-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/europainversi.org\/wp-content\/uploads\/2023\/05\/2023-05-20_17-45-04_1-300x200.jpg 300w, https:\/\/europainversi.org\/wp-content\/uploads\/2023\/05\/2023-05-20_17-45-04_1-1024x683.jpg 1024w, https:\/\/europainversi.org\/wp-content\/uploads\/2023\/05\/2023-05-20_17-45-04_1-768x512.jpg 768w, https:\/\/europainversi.org\/wp-content\/uploads\/2023\/05\/2023-05-20_17-45-04_1-960x640.jpg 960w, https:\/\/europainversi.org\/wp-content\/uploads\/2023\/05\/2023-05-20_17-45-04_1.jpg 1500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1500,"height":1000,"file":"2023\/05\/2023-05-20_17-45-04_1.jpg","filesize":216770,"sizes":{"medium":{"file":"2023-05-20_17-45-04_1-300x200.jpg","width":300,"height":200,"filesize":63436,"mime_type":"image\/jpeg","source_url":"https:\/\/europainversi.org\/wp-content\/uploads\/2023\/05\/2023-05-20_17-45-04_1-300x200.jpg"},"large":{"file":"2023-05-20_17-45-04_1-1024x683.jpg","width":1024,"height":683,"filesize":140883,"mime_type":"image\/jpeg","source_url":"https:\/\/europainversi.org\/wp-content\/uploads\/2023\/05\/2023-05-20_17-45-04_1-1024x683.jpg"},"thumbnail":{"file":"2023-05-20_17-45-04_1-150x150.jpg","width":150,"height":150,"filesize":56287,"mime_type":"image\/jpeg","source_url":"https:\/\/europainversi.org\/wp-content\/uploads\/2023\/05\/2023-05-20_17-45-04_1-150x150.jpg"},"medium_large":{"file":"2023-05-20_17-45-04_1-768x512.jpg","width":768,"height":512,"filesize":107379,"mime_type":"image\/jpeg","source_url":"https:\/\/europainversi.org\/wp-content\/uploads\/2023\/05\/2023-05-20_17-45-04_1-768x512.jpg"},"custom-header-image":{"file":"2023-05-20_17-45-04_1-960x640.jpg","width":960,"height":640,"filesize":131794,"mime_type":"image\/jpeg","source_url":"https:\/\/europainversi.org\/wp-content\/uploads\/2023\/05\/2023-05-20_17-45-04_1-960x640.jpg"},"full":{"file":"2023-05-20_17-45-04_1.jpg","width":1500,"height":1000,"mime_type":"image\/jpeg","source_url":"https:\/\/europainversi.org\/wp-content\/uploads\/2023\/05\/2023-05-20_17-45-04_1.jpg"}},"image_meta":{"aperture":"7.1","credit":"Lorenzo Caimi","camera":"Canon EOS R5","caption":"","created_timestamp":"1684601104","copyright":"","focal_length":"53","iso":"8000","shutter_speed":"0.008","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/europainversi.org\/wp-content\/uploads\/2023\/05\/2023-05-20_17-45-04_1.jpg","_links":{"self":[{"href":"https:\/\/europainversi.org\/en\/wp-json\/wp\/v2\/media\/9412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/europainversi.org\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/europainversi.org\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/europainversi.org\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/europainversi.org\/en\/wp-json\/wp\/v2\/comments?post=9412"}]}}